{"id":536,"date":"2012-08-25T20:37:01","date_gmt":"2012-08-25T19:37:01","guid":{"rendered":"http:\/\/okavango.lescigales.org\/?p=536"},"modified":"2012-08-25T20:37:01","modified_gmt":"2012-08-25T19:37:01","slug":"reunion-de-passage","status":"publish","type":"post","link":"https:\/\/www.50eme-reine-astrid.be\/okavango\/reunion-de-passage\/","title":{"rendered":"Convocation R\u00e9union de passage"},"content":{"rendered":"<p>La rentr\u00e9e approche et qui dit rentr\u00e9e dit r\u00e9union de passage ! \ud83d\ude42 Vous avez tous re\u00e7u la convocation des chefs d&rsquo;unit\u00e9s pour annoncer que celle-ci aurait lieu le 30 septembre !<\/p>\n<p>On esp\u00e8re vous y voir en pleine forme comme d&rsquo;habitude et nombreux (n&rsquo;h\u00e9sitez pas \u00e0 parler de la troupe autour de vous !).<\/p>\n<p>Les \u00e9ph\u00e9m\u00e9rides du premier quadrimestre sont d\u00e9j\u00e0 disponibles dans l&rsquo;onglet \u00ab\u00a0Agenda\u00a0\u00bb !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La rentr\u00e9e approche et qui dit rentr\u00e9e dit r\u00e9union de passage ! \ud83d\ude42 Vous avez tous re\u00e7u la convocation des chefs d&rsquo;unit\u00e9s pour annoncer que celle-ci aurait lieu le 30 septembre ! On esp\u00e8re vous y voir en pleine forme comme d&rsquo;habitude et nombreux (n&rsquo;h\u00e9sitez pas \u00e0 parler de la troupe autour de vous !). &hellip; <\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-536","post","type-post","status-publish","format-standard","hentry","category-convocations"],"_links":{"self":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts\/536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/comments?post=536"}],"version-history":[{"count":0,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts\/536\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/media?parent=536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/categories?post=536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/tags?post=536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}