{"id":1499,"date":"2014-08-10T21:19:52","date_gmt":"2014-08-10T20:19:52","guid":{"rendered":"http:\/\/www.50eme-reine-astrid.be\/okavango\/?p=1499"},"modified":"2014-08-10T21:19:52","modified_gmt":"2014-08-10T20:19:52","slug":"hamm-2014-step-1-constructions","status":"publish","type":"post","link":"https:\/\/www.50eme-reine-astrid.be\/okavango\/hamm-2014-step-1-constructions\/","title":{"rendered":"Hamm 2014: Step 1: Constructions !"},"content":{"rendered":"<p><a href=\"http:\/\/img15.hostingpics.net\/pics\/463687DSCN0260.jpg\" target=\"blank\"><img decoding=\"async\" class=\"alignleft size-full wp-image-1500\" style=\"width: 400px; margin-bottom: 5px; margin-right: 5px;\" title=\"Bighorn et Abyssin devant le pilotis en construction\" src=\"http:\/\/www.50eme-reine-astrid.be\/wp-content\/uploads\/sites\/2\/DSCN0260_compressed.jpg\" alt=\"Bighorn et Abyssin devant le pilotis en construction\" \/><\/a>Salut les scouts !<\/p>\n<p>Cette fois n&rsquo;est pas coutume: nous avons d\u00e9cid\u00e9 de mettre les photos du camp \u00e0 votre disposition avant m\u00eame de vous avoir montr\u00e9 le film du camp ! Mais vu le nombre cons\u00e9quent de photos, nous ne publierons qu&rsquo;une partie des photos chaque jour, dans l&rsquo;ordre chronologique du camp&#8230;<br \/>\nAujourd&rsquo;hui d\u00e9bute donc ce grand p\u00e9riple dans vos m\u00e9moires et nous commencerons \u00e9videmment par les constructions ! D&rsquo;abord celles du staff pour lesquelles nous nous sommes beaucoup donn\u00e9s. Cette ann\u00e9e, nous avions d\u00e9cid\u00e9 de mettre trois tentes sur pilotis: deux SNJ&rsquo;s et notre canadienne \u00e9videmment.<br \/>\nLes deux premiers jours furent ardus puisqu&rsquo;il n&rsquo;arr\u00eatait pas de pleuvoir. Nous avons d\u00fb creuser des trous couch\u00e9s dans la boue, scier et transporter des b\u00fbmes sous une drache incessante ! Heureusement, une fois les poteaux mis en terre, le soleil nous est r\u00e9apparu, juste \u00e0 temps pour r\u00e9ellement commencer \u00e0 construire ce que nous avions en t\u00eate. Chacun y mettant du sien, nous sommes arriv\u00e9 au bout sans trop de difficult\u00e9s. Une journ\u00e9e enti\u00e8re de tissage fut ensuite n\u00e9cessaire pour combler les 24 lits et espaces de rangements. Et enfin, grande joie quand, apr\u00e8s avoir mont\u00e9 les trois tentes, nous avons finalement pu dormir sur nos confortables paillasses ! \ud83d\ude00<\/p>\n<p>Le 13 juillet arrivaient les CP\u2019s et SP\u2019s. Apr\u00e8s le d\u00e9chargement des nombreux bagages, malles et tentes suivi d\u2019un bon pique-nique tous ensemble, ils ont mont\u00e9 leurs tentes aux endroits indiqu\u00e9s. Les itin\u00e9raires de hike pour chaque patrouille ont \u00e9t\u00e9 d\u00e9termin\u00e9s l\u2019apr\u00e8s-midi. Les six ain\u00e9s ont profit\u00e9 de leur temps libre pour construire un superbe barrage dans la rivi\u00e8re qui longeait la prairie. Gr\u00e2ce \u00e0 celui-ci, les scouts ont pu profiter d\u2019un bassin plus profond que la normale pour se laver et se baigner. Une petite surprise (qui, apparemment, n\u2019\u00e9tait pas vraiment une surprise) \u00e9tait pr\u00e9vue pour la soir\u00e9e : nous sommes tous partis visionner la finale de la Coupe du Monde de football (Allemagne \u2013 Br\u00e9sil) dans un restaurant du village \u00e0 c\u00f4t\u00e9. L\u2019accueil fut tr\u00e8s chaleureux et une pi\u00e8ce avec un projecteur et des enceintes avait \u00e9t\u00e9 pr\u00e9par\u00e9e sp\u00e9cialement pour nous ! Le match s\u2019est sold\u00e9 par un 1-0 pour l\u2019Allemagne et c\u2019\u00e9tait \u00e9videmment la folie dans le restaurant o\u00f9 tout le monde criaient et sautaient ! :p<\/p>\n<p>Le lendemain, le staff a emmen\u00e9 les six ain\u00e9s \u00e0 c\u00f4t\u00e9 d\u2019un lac afin de profiter du soleil et de nager dans l\u2019eau glaciale.<br \/>\nLe 15 juillet, nous avions rendez-vous avec le reste de la troupe. Et pour les quatre jours suivant, ce sont les constructions qui occup\u00e8rent les esprits de tous ! Petit \u00e0 petit, nous avons pu admirer chacun des pilotis qui avan\u00e7aient doucement, au rythme de chacune des patrouilles. Heureusement, le temps \u00e9tait au beau fixe avec un grand soleil omnipr\u00e9sent (parfois m\u00eame trop) ! L\u2019inventivit\u00e9 \u00e9galement \u00e9tait pr\u00e9sente puisque les Cougars avaient pr\u00e9vu un pilotis en W, pour les Grizzlys, nous avions un V tandis que pour les Pumas, c\u2019\u00e9tait un X.<br \/>\nAu bout de ses quatre jours d\u2019effort et de cr\u00e9ativit\u00e9, toutes les tentes \u00e9taient finalement mont\u00e9es sur leur pilotis respectif et les scouts ravis d\u2019enfin pouvoir profiter d\u2019un repos bien m\u00e9rit\u00e9 !<\/p>\n<p>A chacune des trois premi\u00e8res soir\u00e9es du camp, une veill\u00e9e \u00e9tait pr\u00e9par\u00e9e par une patrouille. Nous avons donc eu la chance d\u2019assister aux talents de conteur de certains, de la forte voix d\u2019autres et de la motivation incroyable de la troupe lors des chants et autres sketchs ! Merci \u00e0 vous tous pour ces soir\u00e9es g\u00e9niales ! \ud83d\ude09<br \/>\nLes photos de tous ces \u00e9v\u00e8nements sont disponibles <a style=\"font-weight: bold;\" title=\"Photos du Grand Camp \u00e0 Hamm\" href=\"http:\/\/www.50eme-reine-astrid.be\/Galerie\/index.php?\/category\/86\" target=\"_blank\">sur ce lien<\/a>. N\u2019h\u00e9sitez pas \u00e0 redemander par mail les login et mot de passe si vous les aviez \u00e9gar\u00e9s\u2026 \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salut les scouts ! Cette fois n&rsquo;est pas coutume: nous avons d\u00e9cid\u00e9 de mettre les photos du camp \u00e0 votre disposition avant m\u00eame de vous avoir montr\u00e9 le film du camp ! Mais vu le nombre cons\u00e9quent de photos, nous ne publierons qu&rsquo;une partie des photos chaque jour, dans l&rsquo;ordre chronologique du camp&#8230; Aujourd&rsquo;hui d\u00e9bute &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1499","post","type-post","status-publish","format-standard","hentry","category-comptes-rendus"],"_links":{"self":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/comments?post=1499"}],"version-history":[{"count":9,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts\/1499\/revisions"}],"predecessor-version":[{"id":1509,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts\/1499\/revisions\/1509"}],"wp:attachment":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/media?parent=1499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/categories?post=1499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/tags?post=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}