{"id":1154,"date":"2013-05-07T15:32:04","date_gmt":"2013-05-07T14:32:04","guid":{"rendered":"http:\/\/www.50eme-reine-astrid.be\/okavango\/?p=1154"},"modified":"2013-05-08T22:08:47","modified_gmt":"2013-05-08T21:08:47","slug":"grand-camp-amerois-2013","status":"publish","type":"post","link":"https:\/\/www.50eme-reine-astrid.be\/okavango\/grand-camp-amerois-2013\/","title":{"rendered":"Grand Camp Amerois 2013"},"content":{"rendered":"<p>Comme vous l&rsquo;avez tous appris, cette ann\u00e9e on part aux Amerois ! \ud83d\ude42 Tout le staff a h\u00e2te de passer un camp de dingue avec vous ! <\/p>\n<p>Pour ceux qui ne l&rsquo;auraient pas re\u00e7u, vous pouvez retrouver le carnet de camp : <a href=\"http:\/\/www.50eme-reine-astrid.be\/Documents\/Carnet_Camp_2013.pdf\">ICI<\/a><\/p>\n<p>Temps restant avant le Grand Camp : <\/br><\/br><\/p>\n<p><center><iframe loading=\"lazy\" src=\"http:\/\/www.decompte.net\/compte-a-rebours.php?c=1373882400&#038;s=0&#038;r=0\" width=\"468\" height=\"50\" marginheight=\"0\" marginwidth=\"0\" align=\"middle\" scrolling=\"No\" frameborder=\"0\">iframe d\u00e9sactiv\u00e9e<\/iframe><\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme vous l&rsquo;avez tous appris, cette ann\u00e9e on part aux Amerois ! \ud83d\ude42 Tout le staff a h\u00e2te de passer un camp de dingue avec vous ! Pour ceux qui ne l&rsquo;auraient pas re\u00e7u, vous pouvez retrouver le carnet de camp : ICI Temps restant avant le Grand Camp : iframe d\u00e9sactiv\u00e9e<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1154","post","type-post","status-publish","format-standard","hentry","category-annonces"],"_links":{"self":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts\/1154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/comments?post=1154"}],"version-history":[{"count":11,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts\/1154\/revisions"}],"predecessor-version":[{"id":1167,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/posts\/1154\/revisions\/1167"}],"wp:attachment":[{"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/media?parent=1154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/categories?post=1154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.50eme-reine-astrid.be\/okavango\/wp-json\/wp\/v2\/tags?post=1154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}